{"id":700,"date":"2026-07-05T16:49:37","date_gmt":"2026-07-05T14:49:37","guid":{"rendered":"https:\/\/sabacshelterdogs.andersen-webworks.de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-035\/"},"modified":"2026-07-05T18:01:00","modified_gmt":"2026-07-05T16:01:00","slug":"sabac-drive-2026-07-03-shelter-newpart-035","status":"publish","type":"hund","link":"https:\/\/prihvatilistezapsesabac.org\/de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-035\/","title":{"rendered":"Shelter Dog 032"},"content":{"rendered":"<p>This dog is currently living at the municipal shelter in \u0160abac and is looking for a responsible home.<\/p>\n<p>More details will be added as soon as they are available.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shelter Dog 032 lebt im st\u00e4dtischen Tierheim \u0160abac \u00b7 mittelgro\u00dfer R\u00fcde \u00b7 erwachsener Hund \u00b7 sucht ein Zuhause in Serbien.<\/p>","protected":false},"featured_media":699,"template":"","meta":{"_acf_changed":false,"hund_geburtsdatum":"","hund_hoehe":"46","hund_gewicht":"","hund_kastriert":"","hund_vertraeglich":"","hund_besonderheiten":"","hund_aufenthaltsort":"Municipal shelter \u0160abac","hund_kontakt":"teamwork@strays.de","hund_drive_link":"https:\/\/drive.google.com\/drive\/folders\/1i7Ag17pA32evWXVpcQ7wbJH2xkOHGGHo?usp=drive_link","hund_chipnummer":"688035000305645","hund_import_id":"drive-2026-07-03-shelter-newpart-035","hund_import_batch":"drive-2026-07-03","hund_source_sheet":"Shelter_newPart","hund_source_row":"35","footnotes":""},"geschlecht":[22],"groesse":[19],"alter":[],"vermittlungsstatus":[20],"class_list":["post-700","hund","type-hund","status-publish","has-post-thumbnail","hentry","geschlecht-rude","groesse-mittel-2","vermittlungsstatus-vermittelbar-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund"}],"about":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/types\/hund"}],"version-history":[{"count":1,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/700\/revisions"}],"predecessor-version":[{"id":839,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/700\/revisions\/839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"geschlecht","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/geschlecht?post=700"},{"taxonomy":"groesse","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/groesse?post=700"},{"taxonomy":"alter","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/alter?post=700"},{"taxonomy":"vermittlungsstatus","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/vermittlungsstatus?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}