{"id":676,"date":"2026-07-05T16:49:22","date_gmt":"2026-07-05T14:49:22","guid":{"rendered":"https:\/\/sabacshelterdogs.andersen-webworks.de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-022\/"},"modified":"2026-07-05T18:00:56","modified_gmt":"2026-07-05T16:00:56","slug":"sabac-drive-2026-07-03-shelter-newpart-022","status":"publish","type":"hund","link":"https:\/\/prihvatilistezapsesabac.org\/de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-022\/","title":{"rendered":"Aaron"},"content":{"rendered":"<p>Aaron is currently living at the municipal shelter in \u0160abac and is looking for a responsible home.<\/p>\n<p>The shelter notes describe this dog as: very sweet and friendly dog, calm energy, likes people, lives with other dogs.<\/p>\n<p>For the latest details, please contact Strays e.V. or the shelter team.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aaron lebt im st\u00e4dtischen Tierheim \u0160abac. Er ist freundlich und sucht die N\u00e4he zu Menschen. Er zeigt sich eher ruhig und entspannt.<\/p>","protected":false},"featured_media":675,"template":"","meta":{"_acf_changed":false,"hund_geburtsdatum":"","hund_hoehe":"56","hund_gewicht":"24","hund_kastriert":"","hund_vertraeglich":"dogs, people","hund_besonderheiten":"very sweet and friendly dog, calm energy, likes people, lives with other dogs","hund_aufenthaltsort":"Municipal shelter \u0160abac","hund_kontakt":"teamwork@strays.de","hund_drive_link":"https:\/\/drive.google.com\/drive\/folders\/1uHdAwJt_MYlqlVQ3Q0FOBr08x0m7Z-m_?usp=drive_link","hund_chipnummer":"68803500019347","hund_import_id":"drive-2026-07-03-shelter-newpart-022","hund_import_batch":"drive-2026-07-03","hund_source_sheet":"Shelter_newPart","hund_source_row":"22","footnotes":""},"geschlecht":[22],"groesse":[23],"alter":[],"vermittlungsstatus":[20],"class_list":["post-676","hund","type-hund","status-publish","has-post-thumbnail","hentry","geschlecht-rude","groesse-gros","vermittlungsstatus-vermittelbar-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund"}],"about":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/types\/hund"}],"version-history":[{"count":1,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/676\/revisions"}],"predecessor-version":[{"id":827,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/676\/revisions\/827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media\/675"}],"wp:attachment":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media?parent=676"}],"wp:term":[{"taxonomy":"geschlecht","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/geschlecht?post=676"},{"taxonomy":"groesse","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/groesse?post=676"},{"taxonomy":"alter","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/alter?post=676"},{"taxonomy":"vermittlungsstatus","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/vermittlungsstatus?post=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}