{"id":638,"date":"2026-07-05T16:48:59","date_gmt":"2026-07-05T14:48:59","guid":{"rendered":"https:\/\/sabacshelterdogs.andersen-webworks.de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-003\/"},"modified":"2026-07-05T18:00:45","modified_gmt":"2026-07-05T16:00:45","slug":"sabac-drive-2026-07-03-shelter-newpart-003","status":"publish","type":"hund","link":"https:\/\/prihvatilistezapsesabac.org\/de\/hunde\/sabac-drive-2026-07-03-shelter-newpart-003\/","title":{"rendered":"Shelter Dog 002"},"content":{"rendered":"<p>This dog is currently living at the municipal shelter in \u0160abac and is looking for a responsible home.<\/p>\n<p>More details will be added as soon as they are available.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shelter Dog 002 lebt im st\u00e4dtischen Tierheim \u0160abac \u00b7 mittelgro\u00dfe H\u00fcndin \u00b7 erwachsener Hund \u00b7 sucht ein Zuhause in Serbien.<\/p>","protected":false},"featured_media":637,"template":"","meta":{"_acf_changed":false,"hund_geburtsdatum":"","hund_hoehe":"49","hund_gewicht":"","hund_kastriert":"","hund_vertraeglich":"","hund_besonderheiten":"","hund_aufenthaltsort":"Municipal shelter \u0160abac","hund_kontakt":"teamwork@strays.de","hund_drive_link":"https:\/\/drive.google.com\/drive\/folders\/1vDj9U4g6f8_nt80gPobP2bYWEtrceNW9?usp=drive_link","hund_chipnummer":"6887000000058494","hund_import_id":"drive-2026-07-03-shelter-newpart-003","hund_import_batch":"drive-2026-07-03","hund_source_sheet":"Shelter_newPart","hund_source_row":"3","footnotes":""},"geschlecht":[18],"groesse":[19],"alter":[21],"vermittlungsstatus":[20],"class_list":["post-638","hund","type-hund","status-publish","has-post-thumbnail","hentry","geschlecht-hundin","groesse-mittel-2","alter-erwachsen-2","vermittlungsstatus-vermittelbar-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund"}],"about":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/types\/hund"}],"version-history":[{"count":1,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/638\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/hund\/638\/revisions\/808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media\/637"}],"wp:attachment":[{"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"geschlecht","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/geschlecht?post=638"},{"taxonomy":"groesse","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/groesse?post=638"},{"taxonomy":"alter","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/alter?post=638"},{"taxonomy":"vermittlungsstatus","embeddable":true,"href":"https:\/\/prihvatilistezapsesabac.org\/de\/wp-json\/wp\/v2\/vermittlungsstatus?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}